{"id":759,"date":"2019-08-23T00:00:00","date_gmt":"2019-08-23T04:00:00","guid":{"rendered":"https:\/\/rjm.local\/bridges-august-23-2019\/"},"modified":"2019-08-23T00:00:00","modified_gmt":"2019-08-23T04:00:00","slug":"bridges-august-23-2019","status":"publish","type":"post","link":"https:\/\/rjmusa.org\/es\/puentes-23-agosto-2019\/","title":{"rendered":"Puentes, 23 de agosto de 2019"},"content":{"rendered":"<p><strong><em>FELICIDADES A MIDDIA DOUTE, RJM<\/em><\/strong><\/p>\n<p>El 10 de agosto, Middia Doute hizo sus votos temporales (izquierda), como Religiosa de Jes\u00fas y Mar\u00eda, en Canape Vert, Hait\u00ed. A la derecha, Hna. Marge Perron, RJM, Provincial, le presenta las Constituciones de la Congregaci\u00f3n. Es posible que ya haya recibido la carta de la hermana Marge detallando la ceremonia, pero para asegurarse, se adjunta una copia al correo electr\u00f3nico que acompa\u00f1a a Bridges. \u00a1Tambi\u00e9n se adjuntan hermosas fotos de la ceremonia que seguramente querr\u00e1s ver!<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>DOCUMENTOS OCASIONALES DE VERANO DE LCWR<\/em><\/strong><\/p>\n<p>Queridas hermanas,<\/p>\n<p>S\u00f3lo para informarles que LCWR todav\u00eda tiene a la venta, algunos n\u00fameros del&nbsp;<u>Edici\u00f3n de verano de los peri\u00f3dicos ocasionales<\/u>, con derecho &quot;<strong><em>Nuestra b\u00fasqueda de significado<\/em><\/strong>\u201d.  Algunos de ustedes ya tienen copias individuales y\/o una copia para su comunidad.<\/p>\n<p>Esta edici\u00f3n est\u00e1 llena de profunda inspiraci\u00f3n, temas desafiantes y que expanden el coraz\u00f3n para los tiempos y situaciones que vivimos.<\/p>\n<p>Para \u201cabrir el apetito\u201d, los t\u00edtulos de los Cap\u00edtulos son:<\/p>\n<ul>\n<li>El papel de la creaci\u00f3n de significado en tiempos de transici\u00f3n<\/li>\n<li>Vivir de las grandes preguntas<\/li>\n<li>Interculturalidad: desaf\u00edos y dones para la vida religiosa<\/li>\n<li>Una vida religiosa intercongregacional: explorando las conexiones entre nosotros<\/li>\n<li>Monjas y nadie: una b\u00fasqueda compartida de significado<\/li>\n<li>Redimensionamiento: un llamado al futuro<\/li>\n<li>Escuchar el significado: un examen<\/li>\n<\/ul>\n<p>Si hay alguien m\u00e1s que quiera pedir una copia para usted o una copia para su comunidad,&nbsp;<strong>por favor h\u00e1gamelo saber<\/strong>&nbsp;<strong>lo antes posible<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>gracias rita<\/p>","protected":false},"excerpt":{"rendered":"<p>FELICIDADES A MIDDIA DOUTE, RJM El 10 de agosto, Middia Doute hizo sus votos temporales (izquierda), como\u2026<\/p>","protected":false},"author":2,"featured_media":758,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[1],"tags":[],"our_priorities":[],"section":[188],"class_list":["post-759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsletter","section-bridges"],"acf":[],"taxonomy_info":{"category":[{"value":1,"label":"Bridges"}],"section":[{"value":188,"label":"Bridges"}]},"featured_image_src_large":["https:\/\/rjmusa.org\/wp-content\/uploads\/2019\/09\/Picture1_1.png",625,1023,false],"author_info":{"display_name":"root","author_link":"https:\/\/rjmusa.org\/es\/author\/root\/"},"comment_info":0,"category_info":[{"term_id":1,"name":"Bridges","slug":"newsletter","term_group":0,"term_taxonomy_id":1,"taxonomy":"category","description":"","parent":0,"count":436,"filter":"raw","cat_ID":1,"category_count":436,"category_description":"","cat_name":"Bridges","category_nicename":"newsletter","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/rjmusa.org\/es\/wp-json\/wp\/v2\/posts\/759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rjmusa.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rjmusa.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rjmusa.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rjmusa.org\/es\/wp-json\/wp\/v2\/comments?post=759"}],"version-history":[{"count":0,"href":"https:\/\/rjmusa.org\/es\/wp-json\/wp\/v2\/posts\/759\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rjmusa.org\/es\/wp-json\/wp\/v2\/media\/758"}],"wp:attachment":[{"href":"https:\/\/rjmusa.org\/es\/wp-json\/wp\/v2\/media?parent=759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rjmusa.org\/es\/wp-json\/wp\/v2\/categories?post=759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rjmusa.org\/es\/wp-json\/wp\/v2\/tags?post=759"},{"taxonomy":"our_priorities","embeddable":true,"href":"https:\/\/rjmusa.org\/es\/wp-json\/wp\/v2\/our_priorities?post=759"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/rjmusa.org\/es\/wp-json\/wp\/v2\/section?post=759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}